 {"id":1051,"date":"2021-12-10T16:30:09","date_gmt":"2021-12-10T15:30:09","guid":{"rendered":"https:\/\/www.maisonleleu.atelier-demo.fr\/?post_type=leleu-collaboration&#038;p=1051"},"modified":"2022-02-04T11:45:58","modified_gmt":"2022-02-04T10:45:58","slug":"maison-lelievre","status":"publish","type":"leleu-collaboration","link":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/","title":{"rendered":"x Maison Lelievre"},"content":{"rendered":"<p>Two of France&#8217;s top decorating houses have collaborated to create the &#8220;Retrospective&#8221; Collection. <\/p>\n<p>This collection of contemporary and perfectly coordinated fabrics and wallpapers is based on the emblematic archive designs of the House of LELEU and published by Lelievre Paris.<\/p>\n","protected":false},"featured_media":466,"template":"","class_list":["post-1051","leleu-collaboration","type-leleu-collaboration","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>x Maison Lelievre - Maison Leleu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"x Maison Lelievre - Maison Leleu\" \/>\n<meta property=\"og:description\" content=\"Two of France&#8217;s top decorating houses have collaborated to create the &#8220;Retrospective&#8221; Collection. This collection of contemporary and perfectly coordinated fabrics and wallpapers is based on the emblematic archive designs of the House of LELEU and published by Lelievre Paris.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/\" \/>\n<meta property=\"og:site_name\" content=\"Maison Leleu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MaisonLELEU\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-04T10:45:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/11\/lelievremax.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"912\" \/>\n\t<meta property=\"og:image:height\" content=\"970\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/\",\"url\":\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/\",\"name\":\"x Maison Lelievre - Maison Leleu\",\"isPartOf\":{\"@id\":\"https:\/\/www.maisonleleu.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/11\/lelievremax.jpg\",\"datePublished\":\"2021-12-10T15:30:09+00:00\",\"dateModified\":\"2022-02-04T10:45:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#primaryimage\",\"url\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/11\/lelievremax.jpg\",\"contentUrl\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/11\/lelievremax.jpg\",\"width\":912,\"height\":970},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.maisonleleu.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"x Maison Lelievre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.maisonleleu.com\/#website\",\"url\":\"https:\/\/www.maisonleleu.com\/\",\"name\":\"Maison Leleu\",\"description\":\"Maison de d\u00e9coration - mobilier, luminaires &amp; tapis\",\"publisher\":{\"@id\":\"https:\/\/www.maisonleleu.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.maisonleleu.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.maisonleleu.com\/#organization\",\"name\":\"Maison Leleu\",\"url\":\"https:\/\/www.maisonleleu.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.maisonleleu.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/09\/logo.svg\",\"contentUrl\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/09\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Maison Leleu\"},\"image\":{\"@id\":\"https:\/\/www.maisonleleu.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MaisonLELEU\/\",\"https:\/\/www.instagram.com\/maisonleleu\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"x Maison Lelievre - Maison Leleu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/","og_locale":"en_US","og_type":"article","og_title":"x Maison Lelievre - Maison Leleu","og_description":"Two of France&#8217;s top decorating houses have collaborated to create the &#8220;Retrospective&#8221; Collection. This collection of contemporary and perfectly coordinated fabrics and wallpapers is based on the emblematic archive designs of the House of LELEU and published by Lelievre Paris.","og_url":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/","og_site_name":"Maison Leleu","article_publisher":"https:\/\/www.facebook.com\/MaisonLELEU\/","article_modified_time":"2022-02-04T10:45:58+00:00","og_image":[{"width":912,"height":970,"url":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/11\/lelievremax.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/","url":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/","name":"x Maison Lelievre - Maison Leleu","isPartOf":{"@id":"https:\/\/www.maisonleleu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#primaryimage"},"image":{"@id":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/11\/lelievremax.jpg","datePublished":"2021-12-10T15:30:09+00:00","dateModified":"2022-02-04T10:45:58+00:00","breadcrumb":{"@id":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#primaryimage","url":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/11\/lelievremax.jpg","contentUrl":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/11\/lelievremax.jpg","width":912,"height":970},{"@type":"BreadcrumbList","@id":"https:\/\/www.maisonleleu.com\/en\/leleu-collaboration\/maison-lelievre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.maisonleleu.com\/en\/"},{"@type":"ListItem","position":2,"name":"x Maison Lelievre"}]},{"@type":"WebSite","@id":"https:\/\/www.maisonleleu.com\/#website","url":"https:\/\/www.maisonleleu.com\/","name":"Maison Leleu","description":"Maison de d\u00e9coration - mobilier, luminaires &amp; tapis","publisher":{"@id":"https:\/\/www.maisonleleu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maisonleleu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.maisonleleu.com\/#organization","name":"Maison Leleu","url":"https:\/\/www.maisonleleu.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.maisonleleu.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/09\/logo.svg","contentUrl":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/09\/logo.svg","width":1,"height":1,"caption":"Maison Leleu"},"image":{"@id":"https:\/\/www.maisonleleu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MaisonLELEU\/","https:\/\/www.instagram.com\/maisonleleu\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/leleu-collaboration\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/leleu-collaboration"}],"about":[{"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/types\/leleu-collaboration"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/media\/466"}],"wp:attachment":[{"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/media?parent=1051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}