 {"id":18532,"date":"2022-06-29T15:19:37","date_gmt":"2022-06-29T13:19:37","guid":{"rendered":"https:\/\/www.maisonleleu.com\/?p=18532"},"modified":"2022-06-29T15:19:37","modified_gmt":"2022-06-29T13:19:37","slug":"leventail-3","status":"publish","type":"post","link":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/","title":{"rendered":"L&#8217;\u00e9ventail"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":18367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[],"class_list":["post-18532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;\u00e9ventail - Maison Leleu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;\u00e9ventail - Maison Leleu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Maison Leleu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MaisonLELEU\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T13:19:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"505\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agence34\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agence34\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/\"},\"author\":{\"name\":\"Agence34\",\"@id\":\"https:\/\/www.maisonleleu.com\/#\/schema\/person\/e3478666ee93e4b9d14f141909fb9c94\"},\"headline\":\"L&#8217;\u00e9ventail\",\"datePublished\":\"2022-06-29T13:19:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/\"},\"wordCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.maisonleleu.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg\",\"articleSection\":[\"Press\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/\",\"url\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/\",\"name\":\"L'\u00e9ventail - Maison Leleu\",\"isPartOf\":{\"@id\":\"https:\/\/www.maisonleleu.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg\",\"datePublished\":\"2022-06-29T13:19:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#primaryimage\",\"url\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg\",\"contentUrl\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg\",\"width\":505,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.maisonleleu.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;\u00e9ventail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.maisonleleu.com\/#website\",\"url\":\"https:\/\/www.maisonleleu.com\/\",\"name\":\"Maison Leleu\",\"description\":\"Maison de d\u00e9coration - mobilier, luminaires &amp; tapis\",\"publisher\":{\"@id\":\"https:\/\/www.maisonleleu.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.maisonleleu.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.maisonleleu.com\/#organization\",\"name\":\"Maison Leleu\",\"url\":\"https:\/\/www.maisonleleu.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.maisonleleu.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/09\/logo.svg\",\"contentUrl\":\"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/09\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Maison Leleu\"},\"image\":{\"@id\":\"https:\/\/www.maisonleleu.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MaisonLELEU\/\",\"https:\/\/www.instagram.com\/maisonleleu\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.maisonleleu.com\/#\/schema\/person\/e3478666ee93e4b9d14f141909fb9c94\",\"name\":\"Agence34\",\"sameAs\":[\"https:\/\/www.maisonleleu.com\/\"],\"url\":\"https:\/\/www.maisonleleu.com\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'\u00e9ventail - Maison Leleu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/","og_locale":"en_US","og_type":"article","og_title":"L'\u00e9ventail - Maison Leleu","og_url":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/","og_site_name":"Maison Leleu","article_publisher":"https:\/\/www.facebook.com\/MaisonLELEU\/","article_published_time":"2022-06-29T13:19:37+00:00","og_image":[{"width":505,"height":655,"url":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg","type":"image\/jpeg"}],"author":"Agence34","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Agence34"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#article","isPartOf":{"@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/"},"author":{"name":"Agence34","@id":"https:\/\/www.maisonleleu.com\/#\/schema\/person\/e3478666ee93e4b9d14f141909fb9c94"},"headline":"L&#8217;\u00e9ventail","datePublished":"2022-06-29T13:19:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/"},"wordCount":2,"publisher":{"@id":"https:\/\/www.maisonleleu.com\/#organization"},"image":{"@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg","articleSection":["Press"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/","url":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/","name":"L'\u00e9ventail - Maison Leleu","isPartOf":{"@id":"https:\/\/www.maisonleleu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#primaryimage"},"image":{"@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg","datePublished":"2022-06-29T13:19:37+00:00","breadcrumb":{"@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maisonleleu.com\/en\/leventail-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#primaryimage","url":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg","contentUrl":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2022\/06\/lenventail-magazine.jpg","width":505,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/www.maisonleleu.com\/en\/leventail-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.maisonleleu.com\/en\/"},{"@type":"ListItem","position":2,"name":"L&#8217;\u00e9ventail"}]},{"@type":"WebSite","@id":"https:\/\/www.maisonleleu.com\/#website","url":"https:\/\/www.maisonleleu.com\/","name":"Maison Leleu","description":"Maison de d\u00e9coration - mobilier, luminaires &amp; tapis","publisher":{"@id":"https:\/\/www.maisonleleu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maisonleleu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.maisonleleu.com\/#organization","name":"Maison Leleu","url":"https:\/\/www.maisonleleu.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.maisonleleu.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/09\/logo.svg","contentUrl":"https:\/\/www.maisonleleu.com\/wp-content\/uploads\/2021\/09\/logo.svg","width":1,"height":1,"caption":"Maison Leleu"},"image":{"@id":"https:\/\/www.maisonleleu.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MaisonLELEU\/","https:\/\/www.instagram.com\/maisonleleu\/"]},{"@type":"Person","@id":"https:\/\/www.maisonleleu.com\/#\/schema\/person\/e3478666ee93e4b9d14f141909fb9c94","name":"Agence34","sameAs":["https:\/\/www.maisonleleu.com\/"],"url":"https:\/\/www.maisonleleu.com"}]}},"_links":{"self":[{"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/posts\/18532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/comments?post=18532"}],"version-history":[{"count":1,"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/posts\/18532\/revisions"}],"predecessor-version":[{"id":18533,"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/posts\/18532\/revisions\/18533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/media\/18367"}],"wp:attachment":[{"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/media?parent=18532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/categories?post=18532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.maisonleleu.com\/en\/wp-json\/wp\/v2\/tags?post=18532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}